{"id":2524,"date":"2024-12-12T12:47:04","date_gmt":"2024-12-12T04:47:04","guid":{"rendered":"https:\/\/iris-opt.com\/?p=2524"},"modified":"2026-03-29T00:14:00","modified_gmt":"2026-03-28T16:14:00","slug":"eink-acep-gallery-vs-chlcd","status":"publish","type":"post","link":"https:\/\/iris-opt.com\/de\/blog\/eink-acep-gallery-vs-chlcd\/","title":{"rendered":"Vergleich der Farb-E-Paper: E Ink Gallery vs ChLCD"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Farb-E-Paper ist der n\u00e4chste Meilenstein in energiesparenden Displaytechnologien. Neben den Vorteilen der Stromersparnis und der Lesbarkeit bei Tageslicht m\u00fcssen Farb-E-Paper die Vollfarbbilder von LCDs und Postern vollst\u00e4ndig wiedergeben k\u00f6nnen, damit E-Paper in Anwendungen mit den h\u00f6chsten Farbanforderungen wie Werbung und intelligentem Einzelhandel Fu\u00df fassen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heute werden wir die Gallery Palette mit E Ink ACeP-Farbtechnologie und den ChLCD mit Cholesterin-Fl\u00fcssigkristall von IRIS Optronics verwenden und jeweils mehrere g\u00e4ngige Testbilder auflegen, um die Unterschiede zwischen den beiden Technologien in Vollfarbanwendungen zu untersuchen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Das Prinzip der E-Paper-ACeP-Galerie<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gallery Palette verwendet die ACeP (Advanced Color ePaper)-Technologie von E Ink, bei der vier Tintenpartikel \u2013 Gelb, Cyan, Magenta und Wei\u00df \u2013 in Mikrokapillaren einer elektronischen Papierfolie platziert werden. Durch Anlegen unterschiedlicher Spannungen werden die Tintenpartikel bewegt, um die \u00fcblicherweise vorkommenden 7 Farben wie Schwarz, Wei\u00df, Rot, Gelb, Blau, Gr\u00fcn und Orange zu erzeugen.<\/p>\n\n\n<style>.kb-image2524_0802c9-96.kb-image-is-ratio-size, .kb-image2524_0802c9-96 .kb-image-is-ratio-size{max-width:600px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image2524_0802c9-96.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image2524_0802c9-96 .kb-image-is-ratio-size{align-self:unset;}.kb-image2524_0802c9-96 figure{max-width:600px;}.kb-image2524_0802c9-96 .image-is-svg, .kb-image2524_0802c9-96 .image-is-svg img{width:100%;}.kb-image2524_0802c9-96 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_0802c9-96\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"490\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/gallery-palette-microcups-min.png\" alt=\"Galerie Palette Mikrobecher\" class=\"kb-img wp-image-2729\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/gallery-palette-microcups-min.png 735w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/gallery-palette-microcups-min-300x200.png 300w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/gallery-palette-microcups-min-18x12.png 18w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><figcaption>Die Micropipetten von Gallery Palette enthalten die Tintenfarben Gelb, Cyan, Magenta und Wei\u00df.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn der E-Paper-Bildschirm Farben anzeigen muss, die \u00fcber die oben genannten 7 Farben hinausgehen, m\u00fcssen diese 7 Farben pr\u00e4zise gemischt werden, um bei Betrachtung aus der Ferne \u00e4hnliche Farben zu simulieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Das gleiche ACeP-Prinzip kommt auch beim neueren <a href=\"https:\/\/iris-opt.com\/de\/blog\/eink-spectra6-vs-chlcd\/\" data-type=\"post\" data-id=\"2730\" target=\"_self\">Spectra 6 E-Paper<\/a> zum Einsatz.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Das Prinzip von ChLCD-E-Papier von IRIS Optronics<\/h2>\n\n\n\n<p class=\"wp-block-paragraph translation-block\"><a href=\"https:\/\/iris-opt.com\/de\/products\/full-color-chlcd\/\" data-type=\"page\" data-id=\"307\" target=\"_self\">Cholesterisches Fl\u00fcssigkristall-E-Paper(ChLCD)<\/a> besteht aus drei \u00fcbereinanderliegenden Fl\u00fcssigkristallschichten, von denen jede jeweils rot (R), gr\u00fcn (G) oder blau (B) reflektiert. Durch unterschiedliche elektrische Felder wird die Drehung der Fl\u00fcssigkristallmolek\u00fcle gesteuert, sodass diese nach Abschalten des elektrischen Feldes stabil in einem Zwischenzustand verbleiben:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Im planaren Zustand sind die Fl\u00fcssigkristallmolek\u00fcle ordentlich angeordnet und k\u00f6nnen Licht bestimmter Wellenl\u00e4ngen reflektieren. In diesem Zustand k\u00f6nnen die Farben des reflektierten Bildes gesehen werden.<\/li>\n\n\n\n<li>Die molekulare Ausrichtung von Fl\u00fcssigkristallen im fokussierten Kegelzustand erm\u00f6glicht die Durchdringung von Licht, wodurch die Farbe der darunter liegenden Schicht sichtbar wird.<\/li>\n<\/ul>\n\n\n<style>.kb-image2524_4f3498-df.kb-image-is-ratio-size, .kb-image2524_4f3498-df .kb-image-is-ratio-size{max-width:600px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image2524_4f3498-df.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image2524_4f3498-df .kb-image-is-ratio-size{align-self:unset;}.kb-image2524_4f3498-df figure{max-width:600px;}.kb-image2524_4f3498-df .image-is-svg, .kb-image2524_4f3498-df .image-is-svg img{width:100%;}.kb-image2524_4f3498-df .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_4f3498-df\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"551\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2023\/10\/different-colors-of-ChLCD-735px-min.png\" alt=\"Wellenl\u00e4ngenbereich des sichtbaren Lichts f\u00fcr das menschliche Auge\" class=\"kb-img wp-image-1044\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2023\/10\/different-colors-of-ChLCD-735px-min.png 735w, https:\/\/iris-opt.com\/wp-content\/uploads\/2023\/10\/different-colors-of-ChLCD-735px-min-300x225.png 300w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><figcaption>Die Molek\u00fclorientierung verschiedener ChLCD-Schichten wird angepasst, um Totalreflexion (wei\u00df), Teilreflexion (grau) und Durchl\u00e4ssigkeit (schwarz) zu erreichen.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Durch die unabh\u00e4ngige Steuerung der drei RGB-Schichten des LCD-Displays <a href=\"https:\/\/iris-opt.com\/de\/blog\/how-color-epaper-works\/\" data-type=\"post\" data-id=\"1023\" target=\"_self\">kann das ChLCD<\/a> letztlich <a href=\"https:\/\/iris-opt.com\/de\/blog\/how-color-epaper-works\/\" data-type=\"post\" data-id=\"1023\" target=\"_self\">16,78 Millionen Farben perfekt darstellen<\/a> und so ein ebenso farbenreiches Bild erzeugen wie ein herk\u00f6mmliches LCD. Daher k\u00f6nnen sowohl LCD- als auch ChLCD-E-Paper-Displays eine reichhaltige Farbdarstellung bieten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Umgebung f\u00fcr Farbtests<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um die Farbwiedergabe von ACeP und ChLCD zu testen, haben wir vier repr\u00e4sentative Bilder verwendet:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rot, Gr\u00fcn, Blau, Cyan, Magenta und Gelb werden in 16 Farbabstufungen zu Wei\u00df oder Schwarz umgewandelt, um die Gleichm\u00e4\u00dfigkeit der Farbstufenumwandlung f\u00fcr Vollfarbtechnologien anzuzeigen.<\/li>\n\n\n\n<li>Orange, Violett, Blau und Gr\u00fcn verschmelzen miteinander, um die Farbverlaufdarstellung der Umwandlung von Farben durch Vollfarbtechnologie zu testen.<\/li>\n\n\n\n<li>Landschaftsbild, Test zur Darstellung von Naturlandschaften mittels Display-Technologie.<\/li>\n\n\n\n<li>Portr\u00e4t, Test zur Anzeige der F\u00e4higkeit zur Darstellung von Personenportr\u00e4ts.<\/li>\n<\/ul>\n\n\n<style>.kb-image2524_3bd51c-91 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_3bd51c-91\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"638\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/test-images-quality95-852px.jpg\" alt=\"Vier Bilder von Personen und Landschaften zur Testung der Vollfarb-Elektronikpapier-Technologie\" class=\"kb-img wp-image-2740\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/test-images-quality95-852px.jpg 852w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/test-images-quality95-852px-300x225.jpg 300w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/test-images-quality95-852px-768x575.jpg 768w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/test-images-quality95-852px-16x12.jpg 16w\" sizes=\"auto, (max-width: 852px) 100vw, 852px\" \/><figcaption>Testen Sie die Vollfarb-E-Papier-Technologie mit (oben links) 16-stufigen Graustufen, (oben rechts) Farbverlauf, (unten links) Landschaft und (unten rechts) menschlichem Bild.<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">16-Bit-Graustufen-Konvertierungsvergleich<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Beim Konvertieren der 16 Graustufen der E Ink ACeP Gallery Palette sind zwar 12 Farbgrenzen sichtbar, aber die Ansicht zeigt kein Cyan (sieht aus wie Gr\u00fcn) und kein Violett (sieht aus wie Hellblau). Neben den diskontinuierlichen Graustufen zeigt die Ansicht ein deutliches Korn, wenn sich die Graustufen \u00e4ndern, da verschieden proportionierte wei\u00dfe Tinte gemischt werden muss.<\/p>\n\n\n<style>.kb-image2524_a024b5-65 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_a024b5-65\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"625\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-16-grayscales-852px-quality98.jpg\" alt=\"E Ink Gallery Palette kann kein Cyan und Lila darstellen\" class=\"kb-img wp-image-2732\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-16-grayscales-852px-quality98.jpg 852w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-16-grayscales-852px-quality98-300x220.jpg 300w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-16-grayscales-852px-quality98-768x563.jpg 768w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-16-grayscales-852px-quality98-16x12.jpg 16w\" sizes=\"auto, (max-width: 852px) 100vw, 852px\" \/><figcaption>Die E Ink Gallery Palette kann kein Cyan und kein Violett darstellen, die Farbabstufungen weisen Diskontinuit\u00e4ten auf und die beigemischte wei\u00dfe Tinte wirkt k\u00f6rnig.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Andererseits sorgt <a href=\"https:\/\/iris-opt.com\/de\/blog\/what-is-chlcd\/\" data-type=\"post\" data-id=\"2716\" target=\"_self\">die ChLCD-Technologie<\/a> von IRIS Optronics daf\u00fcr, dass die Farben jeder einzelnen Zeile perfekt wiedergegeben werden, sodass Rot, Gr\u00fcn, Blau, Cyan, Magenta und Gelb jeweils in ihrer urspr\u00fcnglichen Farbe erscheinen.<\/p>\n\n\n<style>.kb-image2524_db4dec-da .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_db4dec-da\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"639\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-16-grayscales2b-852px-quality100.jpg\" alt=\"ChLCD kann Rot, Gr\u00fcn, Blau, Cyan, Magenta und Gelb perfekt im Farbabstufungsbereich darstellen.\" class=\"kb-img wp-image-2736\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-16-grayscales2b-852px-quality100.jpg 852w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-16-grayscales2b-852px-quality100-300x225.jpg 300w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-16-grayscales2b-852px-quality100-768x576.jpg 768w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-16-grayscales2b-852px-quality100-16x12.jpg 16w\" sizes=\"auto, (max-width: 852px) 100vw, 852px\" \/><figcaption>ChLCD kann Rott\u00f6ne, Gr\u00fcnt\u00f6ne, Blaut\u00f6ne, Cyant\u00f6ne, Magentat\u00f6ne und Gelbt\u00f6ne perfekt darstellen.<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Farbverlauf mit vier Farben<\/h3>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">In dem Farbverlauf, in dem sich die vier Farben Orange, Violett, Blau und Gr\u00fcn miteinander vermischen, wurden bei der \"ACeP Gallery Palette\" aufgrund von Tintenmangel viele Bereiche mit Wei\u00df aufgef\u00fcllt, um die fehlenden Farben zu ersetzen, was zu <a href=\"https:\/\/iris-opt.com\/de\/blog\/epaper-color-gamut\/\" data-type=\"post\" data-id=\"2742\" target=\"_self\">Farbunterbrechungen<\/a> f\u00fchrte.<\/p>\n\n\n<style>.kb-image2524_70dcef-aa .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_70dcef-aa\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"639\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-blending2b-800pxquality98.jpg\" alt=\"Gallery Palette f\u00fcllt fehlende Farbabstufungen mit Wei\u00df auf.\" class=\"kb-img wp-image-2733\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-blending2b-800pxquality98.jpg 852w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-blending2b-800pxquality98-300x225.jpg 300w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-blending2b-800pxquality98-768x576.jpg 768w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-blending2b-800pxquality98-16x12.jpg 16w\" sizes=\"auto, (max-width: 852px) 100vw, 852px\" \/><figcaption>Gallery Palette f\u00fcllt fehlende Farbabstufungen mit Wei\u00df auf.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Da das ChLCD von Rayal Corp. 16,78 Millionen Farben unterst\u00fctzt, k\u00f6nnen alle Mischungen der vier Farben Orange, Violett, Blau und Gr\u00fcn, wenn sie im Bild dargestellt werden m\u00fcssen, vollst\u00e4ndig angezeigt werden.<\/p>\n\n\n<style>.kb-image2524_b40977-23 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_b40977-23\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"852\" height=\"639\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-blending2b-852px-quality100.jpg\" alt=\"ChLCD zeigt die Ergebnisse aller Farbmischungen vollst\u00e4ndig an\" class=\"kb-img wp-image-2737\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-blending2b-852px-quality100.jpg 852w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-blending2b-852px-quality100-300x225.jpg 300w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-blending2b-852px-quality100-768x576.jpg 768w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-blending2b-852px-quality100-16x12.jpg 16w\" sizes=\"auto, (max-width: 852px) 100vw, 852px\" \/><figcaption>ChLCD kann die Ergebnisse verschiedener Farbvermischungen vollst\u00e4ndig darstellen.<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Unterschiede in Landschaftsbildern<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Im Experiment mit Landschaftsbildern f\u00fchrte die Unf\u00e4higkeit der Farbpalette \"Gallery Palette\", leuchtende Gr\u00fcn- und Blaut\u00f6ne zu erzeugen, dazu, dass die Farben von Bl\u00e4ttern und fernen Bergen stumpf erschienen, und abgesehen von der K\u00f6rnigkeit, vermittelte das Gesamtbild den Eindruck eines alten Fotos.<\/p>\n\n\n<style>.kb-image2524_23e611-d8.kb-image-is-ratio-size, .kb-image2524_23e611-d8 .kb-image-is-ratio-size{max-width:600px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image2524_23e611-d8.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image2524_23e611-d8 .kb-image-is-ratio-size{align-self:unset;}.kb-image2524_23e611-d8 figure{max-width:600px;}.kb-image2524_23e611-d8 .image-is-svg, .kb-image2524_23e611-d8 .image-is-svg img{width:100%;}.kb-image2524_23e611-d8 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_23e611-d8\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"774\" height=\"1024\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-scenery-800pxquality90-774x1024.jpg\" alt=\"E Ink ACeP Gallery stellt Landschaftsfotos auf getr\u00fcbte Weise dar\" class=\"kb-img wp-image-2734\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-scenery-800pxquality90-774x1024.jpg 774w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-scenery-800pxquality90-227x300.jpg 227w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-scenery-800pxquality90-768x1016.jpg 768w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-scenery-800pxquality90-9x12.jpg 9w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-palette-scenery-800pxquality90.jpg 800w\" sizes=\"auto, (max-width: 774px) 100vw, 774px\" \/><figcaption>Die von der ACeP Galerie pr\u00e4sentierten Landschaftsfotos sind farblich ged\u00e4mpft.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Das satte Gr\u00fcn und Blau des ChLCD verleihen Landschaftsfotos eine dreidimensionale Tiefe und die Farben sind leuchtender.<\/p>\n\n\n<style>.kb-image2524_050792-9a .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_050792-9a\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-scenery2b-800px-quality93-768x1024.jpg\" alt=\"IRIS ChLCD-Displays zeigen Landschaftsfotos lebendiger und dreidimensionaler an\" class=\"kb-img wp-image-2739\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-scenery2b-800px-quality93-768x1024.jpg 768w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-scenery2b-800px-quality93-225x300.jpg 225w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-scenery2b-800px-quality93-9x12.jpg 9w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-scenery2b-800px-quality93.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>Landschaftsfotos, die auf einem ChLCD angezeigt werden, erscheinen lebendiger und dreidimensionaler.<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Portr\u00e4t-Test<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Da E Ink Gallery Palette nur wenige Farben hat, kann sie die Schatten im Gesicht nicht korrekt darstellen, was dazu f\u00fchrt, dass Gesichter flach und die Haut bleich erscheinen. Auch die Farben der blauen und violetten Blumen au\u00dferhalb des Gesichts wirken stumpf.<\/p>\n\n\n<style>.kb-image2524_f2fbcd-d1 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_f2fbcd-d1\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-portrait-800px-quality93-771x1024.jpg\" alt=\"Das E Ink Gallery-Display weist Gesichter auf, denen es an Dreidimensionalit\u00e4t mangelt.\" class=\"kb-img wp-image-2735\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-portrait-800px-quality93-771x1024.jpg 771w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-portrait-800px-quality93-226x300.jpg 226w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-portrait-800px-quality93-768x1020.jpg 768w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-portrait-800px-quality93-9x12.jpg 9w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/e-ink-gallery-portrait-800px-quality93.jpg 800w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><figcaption>Gesichter, die auf E Ink Gallery-Displays dargestellt werden, sind flach und die Hautt\u00f6ne sind blass.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Einerseits werden die Gesichtsz\u00fcge und das Make-up perfekt auf dem ChLCD dargestellt, und die blauen und violetten Blumen im Hintergrund erscheinen dreidimensionaler und lebendiger.<\/p>\n\n\n<style>.kb-image2524_7540d3-b5 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2524_7540d3-b5\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-portrait2b-800px-quality94-768x1024.jpg\" alt=\"ChLCD kann Gesichter perfekt stereoskopisch darstellen\" class=\"kb-img wp-image-2738\" srcset=\"https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-portrait2b-800px-quality94-768x1023.jpg 768w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-portrait2b-800px-quality94-225x300.jpg 225w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-portrait2b-800px-quality94-9x12.jpg 9w, https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/iris-chlcd-portrait2b-800px-quality94.jpg 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption>ChLCD kann Gesichter perfekt dreidimensional darstellen.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Nach einem Vergleich der beiden E-Paper-Technologien im Vollfarbbereich eignet sich das Cholesterin-LCD besser f\u00fcr <a href=\"https:\/\/iris-opt.com\/de\/applications\/retail-living\/\" data-type=\"page\" data-id=\"321\" target=\"_self\">Digital-Signage-Anwendungen<\/a>, bei denen eine hohe Farbtiefe erforderlich ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie mehr \u00fcber die Anwendung von Farb-E-Paper erfahren m\u00f6chten, kontaktieren Sie uns bitte.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u5f69\u8272\u96fb\u5b50\u7d19\u662f\u7bc0\u80fd\u986f\u793a\u6280\u8853\u7684\u4e0b\u4e00\u500b\u91cc\u7a0b\u7891\uff0c\u9664\u4e86\u64c1\u6709\u7701\u96fb\u3001\u65e5\u5149\u4e0b\u53ef\u8996\u7684\u512a\u9ede\u4ee5\u5916\uff0c\u5f69\u8272\u96fb\u5b50\u7d19\u9700\u8981\u80fd\u5b8c\u5168\u5448\u73feLCD\u53ca\u6d77&#8230;<\/p>","protected":false},"author":1,"featured_media":2726,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[10,9],"tags":[],"class_list":["post-2524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product","category-technology"],"acf":[],"taxonomy_info":{"category":[{"value":10,"label":"\u96fb\u5b50\u7d19\u7522\u54c1"},{"value":9,"label":"\u986f\u793a\u5668\u6280\u8853"}]},"featured_image_src_large":["https:\/\/iris-opt.com\/wp-content\/uploads\/2024\/12\/chlcd-vs-gallery-palette-quality91-1024x713.jpg",1024,713,true],"author_info":{"display_name":"elv","author_link":"https:\/\/iris-opt.com\/de\/author\/elv\/"},"comment_info":0,"category_info":[{"term_id":10,"name":"\u96fb\u5b50\u7d19\u7522\u54c1","slug":"product","term_group":0,"term_taxonomy_id":10,"taxonomy":"category","description":"","parent":0,"count":11,"filter":"raw","cat_ID":10,"category_count":11,"category_description":"","cat_name":"\u96fb\u5b50\u7d19\u7522\u54c1","category_nicename":"product","category_parent":0},{"term_id":9,"name":"\u986f\u793a\u5668\u6280\u8853","slug":"technology","term_group":0,"term_taxonomy_id":9,"taxonomy":"category","description":"","parent":0,"count":9,"filter":"raw","cat_ID":9,"category_count":9,"category_description":"","cat_name":"\u986f\u793a\u5668\u6280\u8853","category_nicename":"technology","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/posts\/2524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/comments?post=2524"}],"version-history":[{"count":0,"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/posts\/2524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/media\/2726"}],"wp:attachment":[{"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/media?parent=2524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/categories?post=2524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iris-opt.com\/de\/wp-json\/wp\/v2\/tags?post=2524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}